{"id":151,"date":"2025-08-21T22:57:23","date_gmt":"2025-08-21T20:57:23","guid":{"rendered":"https:\/\/www.monespacedepaix.com\/?p=151"},"modified":"2025-08-21T23:17:37","modified_gmt":"2025-08-21T21:17:37","slug":"3-outils-simples-pour-transformer-ses-emotions-negatives-en-energie-positive","status":"publish","type":"post","link":"https:\/\/www.monespacedepaix.com\/en\/3-outils-simples-pour-transformer-ses-emotions-negatives-en-energie-positive\/","title":{"rendered":"3 outils simples pour transformer ses \u00e9motions n\u00e9gatives en \u00e9nergie positive"},"content":{"rendered":"<p data-start=\"4089\" data-end=\"4258\">\n<p data-start=\"4089\" data-end=\"4258\">Nos \u00e9motions n\u00e9gatives \u2013 tristesse, peur, frustration \u2013 sont des signaux \u00e0 \u00e9couter, pas des fardeaux \u00e0 fuir. Bien g\u00e9r\u00e9es, elles peuvent devenir une force constructive.<\/p>\n<p data-start=\"4260\" data-end=\"4395\"><strong data-start=\"4260\" data-end=\"4285\">1. L\u2019ancrage corporel<\/strong><br data-start=\"4285\" data-end=\"4288\" \/>Se recentrer sur le corps en posant les pieds au sol, en respirant profond\u00e9ment, aide \u00e0 calmer le mental.<\/p>\n<p data-start=\"4397\" data-end=\"4568\"><strong data-start=\"4397\" data-end=\"4429\">2. La r\u00e9\u00e9criture des pens\u00e9es<\/strong><br data-start=\"4429\" data-end=\"4432\" \/>Identifier une pens\u00e9e n\u00e9gative et la transformer en affirmation positive (ex. : \u201cje n\u2019y arriverai pas\u201d \u2192 \u201cje peux avancer pas \u00e0 pas\u201d).<\/p>\n<p data-start=\"4570\" data-end=\"4729\"><strong data-start=\"4570\" data-end=\"4589\">3. La gratitude<\/strong><br data-start=\"4589\" data-end=\"4592\" \/>Prendre 2 minutes chaque jour pour noter trois choses positives permet de changer son regard et d\u2019orienter l\u2019\u00e9nergie vers le bien-\u00eatre.<\/p>\n<p data-start=\"4731\" data-end=\"4883\">En pratiquant ces outils, vous pouvez transformer vos \u00e9motions n\u00e9gatives en <strong data-start=\"4810\" data-end=\"4834\">puissance int\u00e9rieure<\/strong> et retrouver un meilleur \u00e9quilibre \u00e9motionnel.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nos \u00e9motions n\u00e9gatives \u2013 tristesse, peur, frustration \u2013 sont des signaux \u00e0 \u00e9couter, pas des fardeaux \u00e0 fuir. Bien g\u00e9r\u00e9es, elles peuvent devenir une force constructive.<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>","protected":false},"author":1,"featured_media":170,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pmpro_default_level":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mon-espace-de-paix","pmpro-has-access"],"_links":{"self":[{"href":"https:\/\/www.monespacedepaix.com\/en\/wp-json\/wp\/v2\/posts\/151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monespacedepaix.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.monespacedepaix.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.monespacedepaix.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monespacedepaix.com\/en\/wp-json\/wp\/v2\/comments?post=151"}],"version-history":[{"count":4,"href":"https:\/\/www.monespacedepaix.com\/en\/wp-json\/wp\/v2\/posts\/151\/revisions"}],"predecessor-version":[{"id":178,"href":"https:\/\/www.monespacedepaix.com\/en\/wp-json\/wp\/v2\/posts\/151\/revisions\/178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.monespacedepaix.com\/en\/wp-json\/wp\/v2\/media\/170"}],"wp:attachment":[{"href":"https:\/\/www.monespacedepaix.com\/en\/wp-json\/wp\/v2\/media?parent=151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.monespacedepaix.com\/en\/wp-json\/wp\/v2\/categories?post=151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.monespacedepaix.com\/en\/wp-json\/wp\/v2\/tags?post=151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}